{"id":679,"date":"2026-05-05T13:39:22","date_gmt":"2026-05-05T06:39:22","guid":{"rendered":"https:\/\/massamanofficial.com\/?post_type=product&#038;p=679"},"modified":"2026-05-05T13:42:41","modified_gmt":"2026-05-05T06:42:41","slug":"bgpu-trading-leg-2","status":"publish","type":"product","link":"https:\/\/massamanofficial.com\/en\/product\/bgpu-trading-leg-2\/","title":{"rendered":"\ud835\uddd5\ud835\uddda\ud835\udde3\ud835\udde8 \ud835\udde2\ud835\uddd9\ud835\uddd9\ud835\udddc\ud835\uddd6\ud835\udddc\ud835\uddd4\ud835\udddf \ud835\udde7\ud835\udde5\ud835\uddd4\ud835\uddd7\ud835\udddc\ud835\udde1\ud835\uddda \ud835\uddd6\ud835\uddd4\ud835\udde5\ud835\uddd7 \ud835\udfee\ud835\udfec\ud835\udfee\ud835\udff1\/\ud835\udfee\ud835\udff2 \ud835\udddf\ud835\uddd8\ud835\uddda \ud835\udfee"},"content":{"rendered":"<div class=\"checklist-row\">\n<div class=\"checklist-col\">\n<h3>\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d \u0e40\u0e1a\u0e2a\u0e01\u0e32\u0e23\u0e4c\u0e14 (23 \u0e41\u0e1a\u0e1a)<\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>SANCHAI NONTASILA<\/li>\n<li>KRITSADA KAMAN<\/li>\n<li>SARACH YOOYEN<\/li>\n<li>EKANIT PANYA<\/li>\n<li>SURACHAT SAREEPIM<\/li>\n<li>PATRIK GUSTAVSSON<\/li>\n<li>TOMOYUKI DOI<\/li>\n<li>RIKU MATSUDA<\/li>\n<li>NIKA SANDOKHADZE<\/li>\n<li>GAKUTO NOTSUDA<\/li>\n<\/ol>\n\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"78\" class=\"elementor elementor-78\">\n\t\t\t\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-5bec6d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5bec6d5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c67eda9\" data-id=\"c67eda9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fc64d1 card-info eae-pop-btn-type-text elementor-widget elementor-widget-wts-modal-popup\" data-id=\"5fc64d1\" data-element_type=\"widget\" data-widget_type=\"wts-modal-popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"eae-popup-wrapper eae-popup-1855245223\" data-id=\"1855245223\"\n\t\t\tdata-preview-modal=\"\" data-close-button-type=\"icon\"\n\t\t\tdata-close-btn=\"fas fa-times\" data-close-in-out=\"true\" data-effect =\"zoom-in\">\n\t\t\t<a class=\"eae-popup-link icon-position-before\"\n\t\t\tdata-id=\"1855245223\" data-ctrl-id=\"5fc64d1\" href=\"#1855245223\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eae-popup-btn-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eae-popup-btn-text\">\n\t\t\t\t\t\t\tView Full List\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\n\t\t<div id=\"1855245223\" class=\"eae-popup-1855245223 mfp-hide eae-popup-container\">\n\t\t\t<div class=\"eae-popup-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-modal-content\">\n\t\t\t\t\t\t<p><p>1.SANCHAI NONTASILA<br \/>\n2.KRITSADA KAMAN<br \/>\n3.SARACH YOOYEN<br \/>\n4.EKANIT PANYA<br \/>\n5.SURACHAT SAREEPIM<br \/>\n6.PATRIK GUSTAVSSON<br \/>\n7.TOMOYUKI DOI<br \/>\n8.RIKU MATSUDA<br \/>\n9.NIKA SANDOKHADZE<br \/>\n10.GAKUTO NOTSUDA<br \/>\n11.CHANATHIP SONGKRASIN<br \/>\n12.THANAWAT PIMYOTHA<br \/>\n13.SARANON ANUIN<br \/>\n14.YOSHIAKI TAKAGI<br \/>\n15.YUSEF ELIAS DOLAH<br \/>\n16.NALAWICH INTACHAROEN<br \/>\n17.CHANASORN KAEWYOS<br \/>\n18.WITTHAWAT PHRAOTHAISONG<br \/>\n19.IKHSAN FANDI AHMAD<br \/>\n20. RABBITS MAN<br \/>\n21.HOME JERSEY<br \/>\n22.AWAY JERSEY<br \/>\n23.THIRD JERSEY<\/p>\n<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"checklist-col\">\n<h3>\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d \u0e2d\u0e34\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e17\u0e01\u0e32\u0e23\u0e4c\u0e14 (19 \u0e41\u0e1a\u0e1a) \u0e23\u0e31\u0e19\u0e19\u0e31\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c \/103<\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>RANIEL SANATANA DE VASCONCELOS<\/li>\n<li>PATRIK GUSTAVSSON<\/li>\n<li>RIKU MATSUDA<\/li>\n<li>PICHAYA CHAIWARANGKUN<\/li>\n<li>NATHAN JAMES<\/li>\n<li>THANAWAT PIMYOTHA<\/li>\n<li>PONGRAWIT JANTAWONG<\/li>\n<li>WARINTHON JAMNONGWAT<\/li>\n<li>ITTHIMON TIPPANET<\/li>\n<li>YOSHIAKI TAKAGI<\/li>\n<\/ol>\n\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"93\" class=\"elementor elementor-93\">\n\t\t\t\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-4826a5a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4826a5a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8235dd4\" data-id=\"8235dd4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7337157 card-info eae-pop-btn-type-text elementor-widget elementor-widget-wts-modal-popup\" data-id=\"7337157\" data-element_type=\"widget\" data-widget_type=\"wts-modal-popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"eae-popup-wrapper eae-popup-1002109229\" data-id=\"1002109229\"\n\t\t\tdata-preview-modal=\"\" data-close-button-type=\"icon\"\n\t\t\tdata-close-btn=\"fas fa-times\" data-close-in-out=\"true\" data-effect =\"zoom-in\">\n\t\t\t<a class=\"eae-popup-link icon-position-before\"\n\t\t\tdata-id=\"1002109229\" data-ctrl-id=\"7337157\" href=\"#1002109229\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eae-popup-btn-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eae-popup-btn-text\">\n\t\t\t\t\t\t\tView Full List\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\n\t\t<div id=\"1002109229\" class=\"eae-popup-1002109229 mfp-hide eae-popup-container\">\n\t\t\t<div class=\"eae-popup-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-modal-content\">\n\t\t\t\t\t\t<p><p>1.RANIEL SANATANA DE VASCONCELOS<br \/>\n2.PATRIK GUSTAVSSON<br \/>\n3.RIKU MATSUDA<br \/>\n4.PICHAYA CHAIWARANGKUN<br \/>\n5.NATHAN JAMES<br \/>\n6.THANAWAT PIMYOTHA<br \/>\n7.PONGRAWIT JANTAWONG<br \/>\n8.WARINTHON JAMNONGWAT<br \/>\n9.ITTHIMON TIPPANET<br \/>\n10.YOSHIAKI TAKAGI<br \/>\n11.PHOUTTHAVONG SANGVILAY<br \/>\n12.YUSEF ELIAS DOLAH<br \/>\n13.NUTTAWUT WONGSAWANG<br \/>\n14.NALAWICH INTACHAROEN<br \/>\n15.CHANASORN KAEWYOS<br \/>\n16.SIWAKORN PONSAN<br \/>\n17.PISAN DOKMAIKAEW<br \/>\n18.WITTHAWAT PHRAOTHAISONG<br \/>\n19.IKHSAN FANDI AHMAD<\/p>\n<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n<div class=\"checklist-col\">\n<h3>\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d \u0e2a\u0e40\u0e1b\u0e40\u0e0a\u0e35\u0e22\u0e25\u0e01\u0e32\u0e23\u0e4c\u0e14 (9 \u0e41\u0e1a\u0e1a) \u0e23\u0e31\u0e19\u0e19\u0e31\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c \/50<br \/>\n\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d \u0e04\u0e2d\u0e21\u0e21\u0e34\u0e04\u0e01\u0e32\u0e23\u0e4c\u0e14 (9 \u0e41\u0e1a\u0e1a) \u0e23\u0e31\u0e19\u0e19\u0e31\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c \/36<br \/>\n\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e25\u0e32\u0e22\u0e40\u0e0b\u0e47\u0e19 (9 \u0e41\u0e1a\u0e1a) \u0e23\u0e31\u0e19\u0e19\u0e31\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c \/45<\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>RANIEL SANATANA DE VASCONCELOS<\/li>\n<li>PATRIK GUSTAVSSON<\/li>\n<li>RIKU MATSUDA<\/li>\n<li>NATHAN JAMES<\/li>\n<li>WARINTHON JAMNONGWAT<\/li>\n<li>YOSHIAKI TAKAGI<\/li>\n<li>PHOUTTHAVONG SANGVILAY<\/li>\n<li>YUSEF ELIAS DOLAH<\/li>\n<li>IKHSAN FANDI AHMAD<\/li>\n<\/ol>\n<\/div>\n<div class=\"checklist-col\">\n<h3>\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d \u0e2d\u0e31\u0e25\u0e15\u0e23\u0e49\u0e32\u0e41\u0e23\u0e23\u0e4c\u0e01\u0e32\u0e23\u0e4c\u0e14 (7 \u0e41\u0e1a\u0e1a) \u0e23\u0e31\u0e19\u0e19\u0e31\u0e21\u0e40\u0e1a\u0e2d\u0e23\u0e4c \/35<\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>KRITSADA KAMAN<\/li>\n<li>NIKA SANDOKHADZE<\/li>\n<li>PISAN DOKMAIKAEW<\/li>\n<li>YUSEF ELIAS DOLAH<\/li>\n<li>WARIS CHOOLTHONG<\/li>\n<li>MATHEUS FORNAZARI CUSTODIO<\/li>\n<li>IKHSAN FANDI AHMAD<\/li>\n<\/ol>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Complete the Masterpiece. \u2728<br \/>\n\ud835\uddd5\ud835\uddda\ud835\udde3\ud835\udde8 \ud835\udde2\ud835\uddd9\ud835\uddd9\ud835\udddc\ud835\uddd6\ud835\udddc\ud835\uddd4\ud835\udddf \ud835\udde7\ud835\udde5\ud835\uddd4\ud835\uddd7\ud835\udddc\ud835\udde1\ud835\uddda \ud835\uddd6\ud835\uddd4\ud835\udde5\ud835\uddd7 \ud835\udfee\ud835\udfec\ud835\udfee\ud835\udff1\/\ud835\udfee\ud835\udff2 \ud835\udddf\ud835\uddd8\ud835\uddda \ud835\udfee<br \/>\n\u0e04\u0e2d\u0e25\u0e40\u0e25\u0e01\u0e0a\u0e31\u0e48\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e17\u0e35\u0e48\u0e41\u0e1f\u0e19\u0e46 The Rabbits \u0e41\u0e25\u0e30\u0e19\u0e31\u0e01\u0e2a\u0e30\u0e2a\u0e21 \u0e15\u0e49\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e1e\u0e25\u0e32\u0e14 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e49\u0e27\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49!<br \/>\n\u200b<br \/>\n\u0e2a\u0e42\u0e21\u0e2a\u0e23 BG Pathum United \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a Massaman \u0e08\u0e31\u0e14\u0e17\u0e33\u201cBGPU Official Trading Card 2025\/26 (Leg 2)\u201d \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e2a\u0e30\u0e2a\u0e21\u0e2a\u0e42\u0e21\u0e2a\u0e23 BG Pathum United \u0e40\u0e25\u0e01\u0e17\u0e35\u0e48 2 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 2025\/26 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23<br \/>\n\u200b<br \/>\n\u0e42\u0e14\u0e22 Trading Card Leg 2 \u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e19\u0e31\u0e01\u0e40\u0e15\u0e30 BGPU \u0e08\u0e32\u0e01\u0e40\u0e25\u0e01 Leg 2 \u0e17\u0e35\u0e48\u0e19\u0e33\u0e17\u0e31\u0e1e\u0e42\u0e14\u0e22 \u201cIKHSAN \/ PATRIK \/ ELIAS DOLOH\u201d \u0e41\u0e25\u0e30 \u0e19\u0e31\u0e01\u0e40\u0e15\u0e30\u0e04\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e2d\u0e35\u0e01\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22<br \/>\n\u200b<br \/>\n\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e2b\u0e49\u0e40\u0e01\u0e47\u0e1a\u0e2a\u0e30\u0e2a\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e08\u0e32\u0e01\u0e04\u0e2d\u0e25\u0e40\u0e25\u0e01\u0e0a\u0e31\u0e48\u0e19 \u0e02\u0e2d\u0e07 Leg 1 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2d\u0e35\u0e01 76 \u0e41\u0e1a\u0e1a<br \/>\n.<br \/>\n\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e08\u0e30\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e2a\u0e30\u0e2a\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \ud835\udff2 \ud835\udde7\ud835\uddf6\ud835\uddf2\ud835\uddff\ud835\ude00 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e49\u0e19 \ud835\udff3\ud835\udff2 \u0e41\u0e1a\u0e1a \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48<br \/>\n\u200b\ud83d\udd39\ud835\uddd5\ud835\uddee\ud835\ude00\ud835\uddf2 \ud835\uddd6\ud835\uddee\ud835\uddff\ud835\uddf1 \ud835\udddc \u0e08\u0e33\u0e19\u0e27\u0e19 23 \u0e41\u0e1a\u0e1a<br \/>\n\u200b\ud83d\udd39\ud835\udddc\ud835\uddfb\ud835\ude00\ud835\uddf2\ud835\uddff\ud835\ude01 \ud835\uddd6\ud835\uddee\ud835\uddff\ud835\uddf1 \ud835\udddc \u0e08\u0e33\u0e19\u0e27\u0e19 19 \u0e41\u0e1a\u0e1a (\u0e23\u0e31\u0e19\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02 \/103)<br \/>\n\u200b\ud83d\udd39\ud835\uddd4\ud835\ude02\ud835\ude01\ud835\uddfc\ud835\uddf4\ud835\uddff\ud835\uddee\ud835\uddfd\ud835\uddf5 \ud835\uddd6\ud835\uddee\ud835\uddff\ud835\uddf1 \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e19\u0e31\u0e01\u0e40\u0e15\u0e30\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e25\u0e32\u0e22\u0e40\u0e0b\u0e47\u0e19 \u0e2a\u0e38\u0e14 Exclusive! \ud835\udddc \u0e08\u0e33\u0e19\u0e27\u0e19 9 \u0e41\u0e1a\u0e1a (\u2728\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e42\u0e2e\u0e42\u0e25\u0e41\u0e01\u0e23\u0e21 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e25\u0e32\u0e22\u0e40\u0e0b\u0e47\u0e19 \u0e41\u0e25\u0e30 \u0e23\u0e31\u0e19\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\/45)<br \/>\n\u200b\ud83d\udd39\ud835\uddd6\ud835\uddfc\ud835\uddfa\ud835\uddf6\ud835\uddf0 \ud835\uddd6\ud835\uddee\ud835\uddff\ud835\uddf1 \ud835\udddc \u0e08\u0e33\u0e19\u0e27\u0e19 9 \u0e41\u0e1a\u0e1a (\u0e23\u0e31\u0e19\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\/36)<br \/>\n\u200b\ud83d\udd39\ud835\udde6\ud835\uddfd\ud835\uddf2\ud835\uddf0\ud835\uddf6\ud835\uddee\ud835\uddf9 \ud835\uddd6\ud835\uddee\ud835\uddff\ud835\uddf1 \ud835\udddc \u0e08\u0e33\u0e19\u0e27\u0e19 9 \u0e41\u0e1a\u0e1a (\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e25\u0e32\u0e22\u0e40\u0e0b\u0e47\u0e19 \u0e41\u0e25\u0e30 \u0e23\u0e31\u0e19\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\/50)<br \/>\n\u200b\ud83d\udd39\ud835\udde8\ud835\uddf9\ud835\ude01\ud835\uddff\ud835\uddee \ud835\udde5\ud835\uddee\ud835\uddff\ud835\uddf2 \ud835\uddd6\ud835\uddee\ud835\uddff\ud835\uddf1 \ud835\udddc \u0e08\u0e33\u0e19\u0e27\u0e19 7 \u0e41\u0e1a\u0e1a (\u0e23\u0e31\u0e19\u0e2b\u0e21\u0e32\u0e22\u0e40\u0e25\u0e02\/35)<br \/>\n&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<br \/>\n\u0e42\u0e14\u0e22\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \u0e43\u0e19\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a Sachet (\u0e0b\u0e2d\u0e07) I Box (\u0e01\u0e25\u0e48\u0e2d\u0e07) \u0e41\u0e25\u0e30 Exclusive Set \ud83d\uded2 :<br \/>\n\u2705\u0e23\u0e32\u0e04\u0e32\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e0b\u0e2d\u0e07\u0e25\u0e30 98\u0e1a\u0e32\u0e17 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e32\u0e23\u0e4c\u0e14 4\u0e43\u0e1a<br \/>\n\u2705\u0e01\u0e25\u0e48\u0e2d\u0e07 590\u0e1a\u0e32\u0e17 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e32\u0e23\u0e4c\u0e14 20\u0e43\u0e1a<br \/>\n\u2705\u0e41\u0e25\u0e30\u0e0a\u0e38\u0e14 \ud835\uddd8\ud835\ude05\ud835\uddf0\ud835\uddf9\ud835\ude02\ud835\ude00\ud835\uddf6\ud835\ude03\ud835\uddf2 \ud835\udde6\ud835\uddf2\ud835\ude01 1 \u0e40\u0e0b\u0e15\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e32\u0e23\u0e4c\u0e14 4 \u0e01\u0e25\u0e48\u0e2d\u0e07 \u0e2b\u0e23\u0e37\u0e2d 76 \u0e43\u0e1a (\u0e23\u0e32\u0e04\u0e32 12,999.-)<br \/>\n\u0e01\u0e32\u0e23\u0e31\u0e19\u0e15\u0e35\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e04\u0e23\u0e1a\u0e17\u0e31\u0e49\u0e07 76 \u0e41\u0e1a\u0e1a \/ \u0e25\u0e32\u0e22\u0e40\u0e0b\u0e47\u0e19\u0e2a\u0e35\u0e17\u0e2d\u0e07\u0e1a\u0e19 Autograph Card \/ \u0e08\u0e33\u0e19\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 \u0e40\u0e1e\u0e35\u0e22\u0e07 20 \u0e40\u0e0b\u0e15\u2757<br \/>\n\u0e2a\u0e38\u0e14\u0e04\u0e38\u0e48\u0e21\u0e22\u0e34\u0e48\u0e07\u0e01\u0e27\u0e48\u0e32\u0e04\u0e38\u0e49\u0e21 \u0e40\u0e1e\u0e23\u0e32\u0e30 \ud835\uddd8\ud835\ude05\ud835\uddf0\ud835\uddf9\ud835\ude02\ud835\ude00\ud835\uddf6\ud835\ude03\ud835\uddf2 \ud835\udde6\ud835\uddf2\ud835\ude01 \u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a<br \/>\n\u200b\u272d \u200b\u0e18\u0e07\u0e41\u0e25\u0e01\u0e2a\u0e42\u0e21\u0e2a\u0e23 BG Pathum United \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e25\u0e32\u0e22\u0e40\u0e0b\u0e47\u0e19\u0e19\u0e31\u0e01\u0e40\u0e15\u0e30\u0e17\u0e31\u0e49\u0e07 11 \u0e04\u0e19<br \/>\n\u272d \u0e2a\u0e21\u0e38\u0e14\u0e2a\u0e30\u0e2a\u0e21\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e42\u0e25\u0e42\u0e01\u0e49\u0e2a\u0e42\u0e21\u0e2a\u0e23 1 \u0e40\u0e25\u0e48\u0e21<br \/>\n\u272d \u0e01\u0e25\u0e48\u0e2d\u0e07 Special Boxset \u0e25\u0e27\u0e14\u0e25\u0e32\u0e22\u0e2a\u0e19\u0e32\u0e21 True BG Stadium<br \/>\n.<br \/>\n\u2b50 \u0e2a\u0e38\u0e14\u0e1e\u0e34\u0e40\u0e28\u0e29! 2 In Boxes \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e49\u0e19\u0e2b\u0e32 \u201c\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e1e\u0e34\u0e40\u0e28\u0e29\u201d \u0e17\u0e35\u0e48\u0e21\u0e35\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48 2 \u0e43\u0e1a \u0e08\u0e32\u0e01\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 20 \u0e01\u0e25\u0e48\u0e2d\u0e07 \u0e02\u0e2d\u0e07 \u201cTrading Card Exclusive Set\u201d \u0e1c\u0e39\u0e49\u0e42\u0e0a\u0e04\u0e14\u0e35\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e2a\u0e38\u0e14 Exclusive \u0e08\u0e32\u0e01\u0e2a\u0e42\u0e21\u0e2a\u0e23 BG Pathum United\u203c\ufe0f<br \/>\n&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<br \/>\n\u0e27\u0e31\u0e19 \u0e40\u0e27\u0e25\u0e32 \u0e41\u0e25\u0e30 \u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22 \ud83d\uded2<br \/>\n\u200b<br \/>\n\ud83d\udcc6 \u0e27\u0e31\u0e19\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e17\u0e35\u0e48 4 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2026<br \/>\n\ud83d\udccd \u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c bgpushop.com<br \/>\n\ud83d\udd54 \u0e40\u0e27\u0e25\u0e32 : 10.00 \u0e19. \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e44\u0e1b<br \/>\n\u200b<br \/>\n\ud83d\udcc6 \u0e27\u0e31\u0e19\u0e2d\u0e31\u0e07\u0e04\u0e32\u0e23 \u0e17\u0e35\u0e48 5 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2026<br \/>\n\ud83d\udccd \u0e23\u0e49\u0e32\u0e19\u0e04\u0e49\u0e32\u0e2a\u0e42\u0e21\u0e2a\u0e23 BGPU Mega Store \u0e13 \u0e2a\u0e19\u0e32\u0e21 True BG Stadium<br \/>\n\ud83d\udd54 \u0e40\u0e27\u0e25\u0e32 : 09.00 \u0e19. \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e44\u0e1b<br \/>\n\u200b<br \/>\n&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<br \/>\n\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2a\u0e31\u0e48\u0e07\u0e0b\u0e37\u0e49\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \ud83d\uded2\ud83c\udf0f<br \/>\n\u200b<br \/>\n\u0e27\u0e32\u0e07\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e17\u0e35\u0e48\u0e41\u0e23\u0e01! \u0e1a\u0e19 \ud835\uddea\ud835\uddd8\ud835\uddd5\ud835\udde6\ud835\udddc\ud835\udde7\ud835\uddd8 (\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c) \u0e41\u0e25\u0e30 \ud835\udddf\ud835\udddc\ud835\udde9\ud835\uddd8 \ud835\udde7\ud835\udddc\ud835\uddde\ud835\udde7\ud835\udde2\ud835\uddde \ud835\udde6\ud835\udddb\ud835\udde2\ud835\udde3<br \/>\n\u200b\ud83d\uded2 \ud835\uddea\ud835\uddf2\ud835\uddef\ud835\ude00\ud835\uddf6\ud835\ude01\ud835\uddf2 : <a href=\"https:\/\/www.bgpushop.com\/prod...\/bgpu-official-trading-card\/\">https:\/\/www.bgpushop.com\/prod&#8230;\/bgpu-official-trading-card\/<\/a><br \/>\n\u200b\ud83d\uded2 \ud835\udde7\ud835\uddf6\ud835\uddf8\ud835\ude01\ud835\uddfc\ud835\uddf8 \ud835\udde6\ud835\uddf5\ud835\uddfc\ud835\uddfd : <a href=\"https:\/\/www.tiktok.com\/@bgpushop\">www.tiktok.com\/@bgpushop<\/a><br \/>\n\u200b<br \/>\n&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<br \/>\n\ud83d\udcac \u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 FB inbox \u0e2b\u0e23\u0e37\u0e2d<br \/>\nLine : @bgpushop \u0e2b\u0e23\u0e37\u0e2d\u0e04\u0e25\u0e34\u0e4a\u0e01\u00a0<a href=\"https:\/\/lin.ee\/mAL3Cyd\">https:\/\/lin.ee\/mAL3Cyd<\/a><\/p>","protected":false},"featured_media":680,"template":"","meta":{"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"product_cat":[16],"product_tag":[],"class_list":["post-679","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-football-card","entry","content-bg","loop-entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/massamanofficial.com\/en\/wp-json\/wp\/v2\/product\/679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/massamanofficial.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/massamanofficial.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/massamanofficial.com\/en\/wp-json\/wp\/v2\/media\/680"}],"wp:attachment":[{"href":"https:\/\/massamanofficial.com\/en\/wp-json\/wp\/v2\/media?parent=679"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/massamanofficial.com\/en\/wp-json\/wp\/v2\/product_cat?post=679"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/massamanofficial.com\/en\/wp-json\/wp\/v2\/product_tag?post=679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}