{"id":590,"date":"2025-06-10T18:51:16","date_gmt":"2025-06-10T11:51:16","guid":{"rendered":"https:\/\/massamanofficial.com\/?post_type=product&#038;p=590"},"modified":"2025-06-11T12:49:50","modified_gmt":"2025-06-11T05:49:50","slug":"police-tero-2024-2025","status":"publish","type":"product","link":"https:\/\/massamanofficial.com\/en\/product\/police-tero-2024-2025\/","title":{"rendered":"\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e2a\u0e30\u0e2a\u0e21\u0e17\u0e35\u0e21\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25 \u0e42\u0e1b\u0e25\u0e34\u0e28\u0e40\u0e17\u0e42\u0e23 \u0e40\u0e2d\u0e1f\u0e0b\u0e35 \u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 2024\/25"},"content":{"rendered":"<div class=\"checklist-row\">\n<div class=\"checklist-col\">\n<h3>\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e40\u0e1a\u0e2a\u0e01\u0e32\u0e23\u0e4c\u0e14 42 \u0e43\u0e1a<\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>Police Tero FC Badge (Short printed)<\/li>\n<li>Stadium (Short printed)<\/li>\n<li>Home Jersey<\/li>\n<li>STARTING XI<\/li>\n<li>COACH<\/li>\n<li>SAHAWIT KHUMPIAM<\/li>\n<li>APICHOK SEERAWONG<\/li>\n<li>SURIYA THATA<\/li>\n<li>ADOLPH KOUDAKPO<\/li>\n<li>WARAWUT MOTIM<\/li>\n<\/ol>\n\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"78\" class=\"elementor elementor-78\">\n\t\t\t\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-5bec6d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5bec6d5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c67eda9\" data-id=\"c67eda9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fc64d1 card-info eae-pop-btn-type-text elementor-widget elementor-widget-wts-modal-popup\" data-id=\"5fc64d1\" data-element_type=\"widget\" data-widget_type=\"wts-modal-popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"eae-popup-wrapper eae-popup-1359195024\" data-id=\"1359195024\"\n\t\t\tdata-preview-modal=\"\" data-close-button-type=\"icon\"\n\t\t\tdata-close-btn=\"fas fa-times\" data-close-in-out=\"true\" data-effect =\"zoom-in\">\n\t\t\t<a class=\"eae-popup-link icon-position-before\"\n\t\t\tdata-id=\"1359195024\" data-ctrl-id=\"5fc64d1\" href=\"#1359195024\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eae-popup-btn-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eae-popup-btn-text\">\n\t\t\t\t\t\t\tView Full List\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\n\t\t<div id=\"1359195024\" class=\"eae-popup-1359195024 mfp-hide eae-popup-container\">\n\t\t\t<div class=\"eae-popup-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-modal-content\">\n\t\t\t\t\t\t<p><p>1.Police Tero FC Badge (Short printed)<br \/>\n2.Stadium (Short printed)<br \/>\n3.Home Jersey<br \/>\n4.STARTING XI<br \/>\n5.COACH<br \/>\n6.SAHAWIT KHUMPIAM<br \/>\n7.APICHOK SEERAWONG<br \/>\n8.SURIYA THATA<br \/>\n9.ADOLPH KOUDAKPO<br \/>\n10.WARAWUT MOTIM<br \/>\n11.FERNANDO VIANA<br \/>\n12.TIRAPON THANACHARTKUN<br \/>\n13.SATTAWAS LEELA<br \/>\n14.ANIPONG KIJKAM<br \/>\n15.SRAYUT SOMPIM<br \/>\n16.AHMED AWAD<br \/>\n17.PHODCHARA CHAINARONG<br \/>\n18.SAMPAN KESI<br \/>\n19.SIRAWUT KENGNOK<br \/>\n20. ZOGBE VIREAK<br \/>\n21.SITTICHOK TUSSANAI<br \/>\n22. SUMANA SALAPPHET<br \/>\n23. SI THU AUNG<\/p>\n<p>U23<br \/>\n24.PICHITCHAI SIENKRATHOK<br \/>\n25.SONGKHRAMSAMUT NAMPHUENG<br \/>\n26.ABDULRAHMAN ESSADI<br \/>\n27.SIRAWAT KAEWMANEEWAN<br \/>\n28.APIDET JANNGAM<br \/>\n29.SIWAKORN WATTHANAWITOONGUL<br \/>\n30.SPHON NOIWONG<br \/>\n31.RATTAPHUM PANKEJOHN<br \/>\n32.PHUMIN WILLIAM BOERS<br \/>\n33.ATSADA HOMHUAL<br \/>\n34.SURIYA MAHASARN<\/p>\n<p>Flash Back (4 Cards)<br \/>\n1. APICHET PUTTAN<br \/>\n2. DATSAKORN THONGLAO<br \/>\n3. PITAKPONG KULSUWAN<br \/>\n4. SHO SHIMOJI<\/p>\n<p>Dragon Legend (4 Cards)<br \/>\n1. APICHET PUTTAN<br \/>\n2. CHAYAPHAT KITPONGSRITHADA<br \/>\n3. DATSAKORN THONGLAO<br \/>\n4. SHO SHIMOJI<\/p>\n<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"checklist-col\">\n<h3>Autograph Card<br \/>\nBasic Autograph card<br \/>\nParallel (\/10 \/1)<\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>SAHAWIT KHUMPIAM<\/li>\n<li>APICHOK SEERAWONG<\/li>\n<li>SURIYA THATA<\/li>\n<li>ADOLPH KOUDAKPO<\/li>\n<li>WARAWUT MOTIM<\/li>\n<li>SONGKHRAMSAMUT NAMPHUENG<\/li>\n<li>ABDULRAHMAN ESSADI<\/li>\n<li>TIRAPON THANACHARTKUN<\/li>\n<li>SATTAWAS LEELA<\/li>\n<li>ANIPONG KIJKAM<\/li>\n<\/ol>\n\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"93\" class=\"elementor elementor-93\">\n\t\t\t\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-4826a5a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4826a5a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8235dd4\" data-id=\"8235dd4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7337157 card-info eae-pop-btn-type-text elementor-widget elementor-widget-wts-modal-popup\" data-id=\"7337157\" data-element_type=\"widget\" data-widget_type=\"wts-modal-popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"eae-popup-wrapper eae-popup-1801432765\" data-id=\"1801432765\"\n\t\t\tdata-preview-modal=\"\" data-close-button-type=\"icon\"\n\t\t\tdata-close-btn=\"fas fa-times\" data-close-in-out=\"true\" data-effect =\"zoom-in\">\n\t\t\t<a class=\"eae-popup-link icon-position-before\"\n\t\t\tdata-id=\"1801432765\" data-ctrl-id=\"7337157\" href=\"#1801432765\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eae-popup-btn-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eae-popup-btn-text\">\n\t\t\t\t\t\t\tView Full List\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\n\t\t<div id=\"1801432765\" class=\"eae-popup-1801432765 mfp-hide eae-popup-container\">\n\t\t\t<div class=\"eae-popup-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-modal-content\">\n\t\t\t\t\t\t<p><p>1.SAHAWIT KHUMPIAM<br \/>\n2.APICHOK SEERAWONG<br \/>\n3.SURIYA THATA<br \/>\n4..ADOLPH KOUDAKPO<br \/>\n5.WARAWUT MOTIM<br \/>\n6.SONGKHRAMSAMUT NAMPHUENG<br \/>\n7.ABDULRAHMAN ESSADI<br \/>\n8.TIRAPON THANACHARTKUN<br \/>\n9.SATTAWAS LEELA<br \/>\n10.ANIPONG KIJKAM<br \/>\n11.SIRAWAT KAEWMANEEWAN<br \/>\n12.SRAYUT SOMPIM<br \/>\n13.AHMED AWAD<br \/>\n14.PHODCHARA CHAINARONG<br \/>\n15.SAMPAN KASEE<br \/>\n16.SIRAWUT KENGNOK<br \/>\n17.ZOGBE VIREAK<br \/>\n18.SITTICHOK TUSSANAI<br \/>\n19.APIDET JANNGAM<br \/>\n20.SPHON NOIWONG<br \/>\n21.SUMANA SALAPPHET<br \/>\n22.PHUMIN WILLIAM BOERS<br \/>\n23.ATSADA HOMHUAL<br \/>\n24.SURIYA MAHASARN<\/p>\n<p>only 1of1<br \/>\nPICHITCHAI SIENKRATHOK<\/p>\n<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"checklist-col\">\n<h3>\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e25\u0e32\u0e22\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e33\u0e19\u0e32\u0e19<br \/>\nDragon Legend Autograph card<\/h3>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<ol>\n<li>APICHET PUTTAN<\/li>\n<li>ANUCHA KIJPONGSRI<\/li>\n<li>DATSAKORN THONGLAO<\/li>\n<li>SHO SHIMOJI<\/li>\n<\/ol>\n\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"97\" class=\"elementor elementor-97\">\n\t\t\t\t\t\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-16bea53 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"16bea53\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8477954\" data-id=\"8477954\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41bc378 card-info eae-pop-btn-type-text elementor-widget elementor-widget-wts-modal-popup\" data-id=\"41bc378\" data-element_type=\"widget\" data-widget_type=\"wts-modal-popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"eae-popup-wrapper eae-popup-772735414\" data-id=\"772735414\"\n\t\t\tdata-preview-modal=\"\" data-close-button-type=\"icon\"\n\t\t\tdata-close-btn=\"fas fa-times\" data-close-in-out=\"true\" data-effect =\"zoom-in\">\n\t\t\t<a class=\"eae-popup-link icon-position-before\"\n\t\t\tdata-id=\"772735414\" data-ctrl-id=\"41bc378\" href=\"#772735414\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eae-popup-btn-icon\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"eae-popup-btn-text\">\n\t\t\t\t\t\t\tView Full List\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\n\t\t<div id=\"772735414\" class=\"eae-popup-772735414 mfp-hide eae-popup-container\">\n\t\t\t<div class=\"eae-popup-content\">\n\t\t\t\t\t\t\t\t\t<div class=\"eae-modal-content\">\n\t\t\t\t\t\t<p><h3>Dragon Legend Autograph card<\/h3>\n<ol>\n<li>APICHET PUTTAN<\/li>\n<li>ANUCHA KIJPONGSRI<\/li>\n<li>DATSAKORN THONGLAO<\/li>\n<li>SHO SHIMOJI<\/li>\n<\/ol>\n<h3>Flash back Autograph card<\/h3>\n<ol>\n<li>APICHET PUTTAN<\/li>\n<li>DATSAKORN THONGLAO<\/li>\n<li>PITAKPONG KULSUWAN<\/li>\n<li>SHO SHIMOJI<\/li>\n<\/ol>\n<h3>Dual Autograph card<\/h3>\n<ol>\n<li>SHO SHIMOJI &amp; APICHET PUTTAN<\/li>\n<li>DATSAKORN THONGLAO &amp; ANUCHA KIJPONGSRI<\/li>\n<\/ol>\n<h3>Triple Autograph card<\/h3>\n<p>APICHET PUTTAN &amp; DATSAKORN THONGLAO &amp; SHO SHIMOJI<\/p>\n<\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"checklist-col\">\n<h3>\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e4c\u0e14 BIG BANG<\/h3>\n<p>&nbsp;<\/p>\n<ol>\n<li>APICHOK SEERAWONG<\/li>\n<li>ADOLPH KOUDAKPO<\/li>\n<\/ol>\n<h3>\u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e4c\u0e14 HOMETOWN<\/h3>\n<ol>\n<li>SONGKHRAMSAMUT NAMPHUENG<\/li>\n<li>ANIPONG KIJKAM<\/li>\n<\/ol>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>\u201cCollect your The Silver Shield Dragons with pride \u0e2a\u0e30\u0e2a\u0e21\u0e40\u0e2b\u0e25\u0e48\u0e32\u0e21\u0e31\u0e07\u0e01\u0e23\u0e42\u0e25\u0e48\u0e2b\u0e4c\u0e40\u0e07\u0e34\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e14\u0e49\u0e27\u0e22\u0e04\u0e27\u0e32\u0e21\u0e20\u0e32\u0e04\u0e20\u0e39\u0e21\u0e34\u0e43\u0e08\u201d<\/p>\n<p>\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e2a\u0e30\u0e2a\u0e21 \ud83d\udc32\ud83d\udee1\ufe0f\u0e42\u0e1b\u0e25\u0e34\u0e28\u0e40\u0e17\u0e42\u0e23 \u0e40\u0e2d\u0e1f\u0e0b\u0e35 \u0e24\u0e14\u0e39\u0e01\u0e32\u0e25 2024\/25<br \/>\nTHE OFFICIAL TRADINGS CARD OF POLICE TERO FC SEASON 2024\/25<br \/>\nGood quality printed cards, glossy glaze, beautiful, durable<br \/>\n\u0e15\u0e35\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e21\u0e32\u0e01\u0e31\u0e19\u0e04\u0e23\u0e1a\u0e17\u0e35\u0e21\u0e40\u0e25\u0e01\u0e2a\u0e2d\u0e07 29\u0e04\u0e19<br \/>\n\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e2d\u0e34\u0e19\u0e40\u0e2a\u0e34\u0e23\u0e4c\u0e17 5\u0e41\u0e1a\u0e1a \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e15\u0e33\u0e19\u0e32\u0e19\u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25 \u0e42\u0e1b\u0e25\u0e34\u0e28\u0e40\u0e17\u0e42\u0e23 8\u0e41\u0e1a\u0e1a \u0e23\u0e27\u0e21\u0e21\u0e35\u0e43\u0e2b\u0e49\u0e2a\u0e30\u0e2a\u0e21\u0e16\u0e36\u0e07 42\u0e41\u0e1a\u0e1a<\/p>\n<p>\ud83d\udccc\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e0a\u0e38\u0e14\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e2a\u0e30\u0e2a\u0e21<br \/>\n\u2705 1\u0e01\u0e25\u0e48\u0e2d\u0e07 \u0e1a\u0e23\u0e23\u0e08\u0e38\u0e01\u0e32\u0e23\u0e4c\u0e14 15\u0e43\u0e1a \u0e23\u0e32\u0e04\u0e32\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e01\u0e25\u0e48\u0e2d\u0e07\u0e25\u0e30 490\u0e1a\u0e32\u0e17 \u0e1c\u0e25\u0e34\u0e15\u0e08\u0e33\u0e19\u0e27\u0e19\u0e08\u0e33\u0e01\u0e31\u0e14 600\u0e01\u0e25\u0e48\u0e2d\u0e07\u2757<br \/>\n\u2705 1\u0e01\u0e25\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e31\u0e19\u0e15\u0e35 \u270d\ufe0f3\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e25\u0e32\u0e22\u0e40\u0e0b\u0e47\u0e19\u2757 \u0e40\u0e0b\u0e47\u0e19\u0e25\u0e07\u0e1a\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e41\u0e1a\u0e1a on card\u203c\ufe0f<br \/>\n\u2705 1\u0e01\u0e25\u0e48\u0e2d\u0e07 \u0e01\u0e32\u0e23\u0e31\u0e19\u0e15\u0e35 \u0e01\u0e32\u0e23\u0e4c\u0e14\u0e15\u0e33\u0e19\u0e32\u0e19\u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25 FLASH BACK \u0e41\u0e25\u0e30 DRAGON LEGEND<br \/>\n\u2705 \u0e25\u0e38\u0e49\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14 Rare \u2728\u0e42\u0e2e\u0e42\u0e25\u0e41\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e2a\u0e35\u0e17\u0e2d\u0e07\ud83d\udfe8 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e40\u0e1e\u0e35\u0e22\u0e07 10\u0e43\u0e1a \u0e43\u0e19\u0e23\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15<br \/>\n\u2705 \u0e25\u0e38\u0e49\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14 Ultra Rare \u2728\u0e42\u0e2e\u0e42\u0e25\u0e41\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e2a\u0e35\u0e14\u0e33\u2b1b \u0e17\u0e35\u0e48\u0e21\u0e35\u0e40\u0e1e\u0e35\u0e22\u0e07 1\u0e43\u0e1a(\ud835\udfcf\ud835\udc28\ud835\udc1f\ud835\udfcf) \u0e43\u0e19\u0e23\u0e2d\u0e1a\u0e1c\u0e25\u0e34\u0e15<br \/>\n\u2705 \u0e25\u0e38\u0e49\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14 Rare \u2728\u0e42\u0e2e\u0e42\u0e25\u0e41\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e4c\u0e14 \u201c\u0e23\u0e30\u0e40\u0e1a\u0e34\u0e14\u0e1e\u0e25\u0e31\u0e07 BIG BANG\ud83d\udca5\u201d \u0e41\u0e25\u0e30 \u0e42\u0e2e\u0e42\u0e25\u0e41\u0e01\u0e23\u0e21\u0e01\u0e32\u0e23\u0e4c\u0e14 \u201c\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e01\u0e34\u0e14 HOMETOWN\ud83c\udfe1\u201d<br \/>\n\u2705 1\u0e40\u0e04\u0e2a \u0e2b\u0e23\u0e37\u0e2d1\u0e25\u0e31\u0e07 (6\u0e01\u0e25\u0e48\u0e2d\u0e07) \u0e23\u0e32\u0e04\u0e32 2,940\u0e1a\u0e32\u0e17 \u0e01\u0e32\u0e23\u0e31\u0e19\u0e15\u0e35\u0e01\u0e32\u0e23\u0e4c\u0e14 Ultra Rare BIG BANG\ud83d\udca5 \u0e41\u0e25\u0e30 HOMETOWN\ud83c\udfe1<br \/>\n\u2705 1\u0e40\u0e04\u0e2a \u0e2b\u0e23\u0e37\u0e2d1\u0e25\u0e31\u0e07 (6\u0e01\u0e25\u0e48\u0e2d\u0e07) \u0e01\u0e32\u0e23\u0e31\u0e19\u0e15\u0e35\u0e01\u0e32\u0e23\u0e4c\u0e14\u270d\ufe0f\u0e25\u0e32\u0e22\u0e40\u0e0b\u0e47\u0e19\u0e15\u0e33\u0e19\u0e32\u0e19\u0e19\u0e31\u0e01\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25 FLASH BACK \u0e41\u0e25\u0e30 DRAGON LEGEND \u0e2b\u0e23\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e4c\u0e14\u270d\ufe0f\u0e25\u0e32\u0e22\u0e40\u0e0b\u0e47\u0e19\u0e04\u0e39\u0e48 Dual Autographed card \u0e2b\u0e23\u0e37\u0e2d Triple Autographed card<\/p>\n<p>Checklist of all cards<\/p>\n<p><a href=\"https:\/\/massamanofficial.com\/en\/product\/police-tero-2024-2025\/\">https:\/\/massamanofficial.com\/product\/police-tero-2024-2025\/<\/a><\/p>\n<p>\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e33\u0e2b\u0e19\u0e48\u0e32\u0e22\u0e41\u0e25\u0e49\u0e27\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e17\u0e32\u0e07 \ud83d\udc47<br \/>\n\u0e0b\u0e37\u0e49\u0e2d\u0e17\u0e35\u0e48\u0e2b\u0e19\u0e49\u0e32\u0e23\u0e49\u0e32\u0e19\ud83c\udfeaShop \u0e2a\u0e42\u0e21\u0e2a\u0e23\u0e2f \u0e2a\u0e19\u0e32\u0e21\u0e01\u0e35\u0e2c\u0e32\u0e1a\u0e38\u0e13\u0e22\u0e30\u0e08\u0e34\u0e19\u0e14\u0e32<br \/>\n<a href=\"https:\/\/maps.app.goo.gl\/mvg2jmmLZTsvuVWH7\">https:\/\/maps.app.goo.gl\/mvg2jmmLZTsvuVWH7<\/a><\/p>\n<p>\u0e0b\u0e37\u0e49\u0e2d\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e17\u0e35\u0e48 \ud83d\udc47<br \/>\nFacebook : Massaman<br \/>\nLine : @massamanofficial<br \/>\n\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07\ud83d\udce6\u0e1e\u0e31\u0e2a\u0e14\u0e38\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e04\u0e48\u0e32\u0e08\u0e31\u0e14\u0e2a\u0e48\u0e07 50\u0e1a\u0e32\u0e17<br \/>\n\u2705 \u0e0a\u0e33\u0e23\u0e30\u0e17\u0e35\u0e48\u0e1a\u0e31\u0e0d\u0e0a\u0e35\u0e18\u0e19\u0e32\u0e04\u0e32\u0e23 \u0e1a\u0e08\u0e01.\u0e21\u0e31\u0e2a\u0e21\u0e31\u0e48\u0e19 \u0e04\u0e2d\u0e25\u0e40\u0e25\u0e04\u0e17\u0e34\u0e40\u0e1a\u0e34\u0e25 \u0e40\u0e17\u0e48\u0e32\u0e19\u0e31\u0e49\u0e19 \u203c\ufe0f<\/p>\n<p>\u0e28\u0e36\u0e01\u0e29\u0e32\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e25\u0e30\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e1f\u0e38\u0e15\u0e1a\u0e2d\u0e25\u0e2a\u0e30\u0e2a\u0e21\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21 \u0e44\u0e14\u0e49\u0e17\u0e35\u0e48\u0e01\u0e25\u0e38\u0e48\u0e21\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22 \u0e0b\u0e37\u0e49\u0e2d-\u0e02\u0e32\u0e22 \u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e01\u0e32\u0e23\u0e4c\u0e14\u0e44\u0e17\u0e22<br \/>\n<a href=\"https:\/\/www.facebook.com\/groups\/740521567221252\">https:\/\/www.facebook.com\/groups\/740521567221252<\/a><\/p>","protected":false},"featured_media":592,"template":"","meta":{"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"product_cat":[16],"product_tag":[],"class_list":["post-590","product","type-product","status-publish","has-post-thumbnail","hentry","product_cat-football-card","entry","content-bg","loop-entry"],"acf":[],"_links":{"self":[{"href":"https:\/\/massamanofficial.com\/en\/wp-json\/wp\/v2\/product\/590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/massamanofficial.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/massamanofficial.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/massamanofficial.com\/en\/wp-json\/wp\/v2\/media\/592"}],"wp:attachment":[{"href":"https:\/\/massamanofficial.com\/en\/wp-json\/wp\/v2\/media?parent=590"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/massamanofficial.com\/en\/wp-json\/wp\/v2\/product_cat?post=590"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/massamanofficial.com\/en\/wp-json\/wp\/v2\/product_tag?post=590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}